{"id":7993,"date":"2024-12-06T10:01:41","date_gmt":"2024-12-06T09:01:41","guid":{"rendered":"https:\/\/www.sondermuenze.ch\/?post_type=magazin&#038;p=7993"},"modified":"2024-12-06T10:19:27","modified_gmt":"2024-12-06T09:19:27","slug":"intervista-a-chiara-principe","status":"publish","type":"magazin","link":"https:\/\/www.sondermuenze.ch\/it\/rivista\/intervista-a-chiara-principe\/","title":{"rendered":"Intervista a Chiara Principe"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"section__text section__text--lead section__text--center intro-animation intro-animation--bottom\">\n<h1>Intervista a<br \/>\nChiara Principe<\/h1>\n<p>La designer di monete Chiara Principe ha disegnato il Vreneli da 100 franchi, che sar\u00e0 presentato per la prima volta l\u2019anno prossimo alla World Money Fair. Cosa si prova ad avere tra le mani una moneta iconica?<\/p>\n<\/div><div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>Il Vreneli \u00e8 una moneta simbolica della Svizzera. Reinventare una moneta come questa \u00e8 una bella sfida. Come ha proceduto nel lavoro?<br \/>\n<\/strong>Quando mi trovo ad accettare un nuovo incarico, in particolare nel caso di un\u2019istituzione statale, per me non si tratta soltanto di lavoro, \u00e8 soprattutto un grande onore e una sfida importante. Come artista e appassionata di monete, ovviamente conoscevo gi\u00e0 il Vreneli, ma non mi sarei mai immaginata che un giorno avrei lavorato a una moneta commemorativa dedicata a questo pezzo. Inizialmente mi immergo il pi\u00f9 possibile nelle origini della moneta stessa, nella sua storia e bellezza. Sono rimasta affascinata dall\u2019artista creatore del Vreneli e dalle interessanti vicende legate al concorso indetto per l\u2019immagine sulla moneta, che l\u2019hanno resa quella che \u00e8 un\u2019icona numismatica in Svizzera. Mi sono sentita profondamente legata a Vreni, una ragazza affascinante e misteriosa, dai tratti e dai vestiti semplici e circondata da un paesaggio che sembra avvolgerla e si rivela essere l\u2019Helvetia per eccellenza. Era cos\u00ec diversa dalle dee romane dall\u2019aspetto regale e nobile cui era abituata la numismatica svizzera, ma forse pi\u00f9 vicina al popolo e per questo amata da tutti.<\/p>\n<\/div><div class=\"section__text section__text--center intro-animation intro-animation--bottom\">\n<h3>\u00abOltre agli approfondimenti artistico-culturali della storia della moneta e alla ricerca di un legame emotivo con l\u2019immagine di Vreni, sono state molto utili anche le conversazioni con i miei amici svizzeri\u00bb.<\/h3>\n<\/div><div class=\"section__teaser_special\"><div class=\"teaser_special row_simple reverse middle-xs \"><div class=\"teaser_special__media col-l-6 col-xs-12 intro-animation-mobile\"><div class=\"picture_container\"><picture><source srcset=\"https:\/\/www.sondermuenze.ch\/wp-content\/uploads\/web-hq-sondermuenze-chiara-620x620px.jpg\"><img decoding=\"async\" src=\"https:\/\/www.sondermuenze.ch\/wp-content\/uploads\/web-hq-sondermuenze-chiara-620x620px.jpg\" alt=\"Chiara Principe\" width=\"620\" height=\"620\"\/><\/picture><\/div><\/div><div class=\"teaser_special__content col-l-6 col-xs-12 intro-animation intro-animation--right\"><div class=\"teaser_special__content__inside\"><p>Oltre agli approfondimenti artistico-culturali della storia della moneta e alla ricerca di un legame emotivo con l\u2019immagine di Vreni, sono state molto utili le conversazioni con i miei amici svizzeri. Le loro testimonianze e le storie delle loro famiglie mi hanno permesso di comprendere a fondo il significato di questa moneta per il popolo svizzero. Celebrare questa storia, questa iconicit\u00e0 e questo \u00abpatrimonio affettivo\u00bb con una nuova moneta che porta tutti questi elementi nella Svizzera moderna \u00e8 stata la grande sfida che spero di aver affrontato con successo insieme a Swissmint.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>Pu\u00f2 descriverci quale significato hanno per Lei il Vreneli in generale e il 100 anni del Vreneli da 100 franchi in particolare?<br \/>\n<\/strong>Ho visto per la prima volta un\u2019immagine del Vreneli durante i miei studi di storia della numismatica. La moneta mi ha impressionato soprattutto per un aspetto che cercher\u00f2 di contestualizzare brevemente. Ha a che fare con la storia del marengo d\u2019oro, una celebre moneta restata in circolo in Europa per poco pi\u00f9 di un secolo dal 1815.<\/p>\n<p>Si trattava di una valuta molto importante, in quanto fu il primo vero tentativo degli Stati europei di creare un\u2019unione monetaria, all\u2019epoca chiamata Unione monetaria latina, cui prese parte anche la Svizzera. Gli Stati che nel 1865 firmarono la convenzione alla base dell\u2019unione (Francia, Italia, Svizzera, Belgio e in seguito Grecia) si impegnarono a coniare le monete conformemente al sistema franco germinale. Tutte le monete d\u2019oro con valore nominale di 20 franchi (compresi i Vreneli) presero il nome di Marenghi d\u2019oro (nota della red.: il franco d\u2019oro corrispondeva al Franco germinale, istituito legalmente il 7 germinale anno XI, il 28 marzo 1803, da Napoleone Bonaparte). Ogni marengo poteva essere scambiato con altri marenghi provenienti da Stati diversi con un rapporto di 1 : 1. Divenne quindi una vera moneta continentale e fu il primo tentativo di moneta unica europea.<\/p>\n\n<h3>\u00abLa moneta per il centenario del Vreneli da 100 franchi rappresenta una nazione saldamente ancorata ai propri valori storici e culturali, che non teme di guardare al futuro forte dei propri valori e della propria identit\u00e0.\u00bb<\/h3>\n\n<p>Ma ci\u00f2 che ho subito notato mentre osservavo le immagini sui cinque marenghi d\u2019oro europei \u00e8 il fatto che quello svizzero fosse l\u2019unica delle cinque monete a recare l\u2019effige di una donna! Ne sono rimasta subito affascinata e ho pensato: che meraviglia! Qualcosa del tipo \u00abwow, ci sono anch\u2019io!\u00bb Non si trattava del profilo di un re o di un sovrano come sugli altri marenghi, ma di una semplice e giovane fanciulla sullo sfondo delle montagne e con i capelli ondeggianti. Rispetto ai suoi \u00abcompagni\u00bb, inquadrati tutti in un contesto storico, il Vreneli sembrava essere una moneta di rara modernit\u00e0. Credo che il fatto che per commemorare questa moneta ci si sia rivolti a un\u2019artista donna abbia un significato molto specifico: nel corso dei secoli, la percezione della donna nella cultura e anche nell\u2019arte ha subito enormi cambiamenti. Si tratta di una tematica oggi come non mai centrale e molto delicata che mi sta molto a cuore. L\u2019opportunit\u00e0 di celebrare il centenario del Vreneli da 100 franchi ha per me in quanto donna e artista un grande valore simbolico e spero che ogni svizzera si senta valorizzata e celebrata come parte vivente della storia, cultura e vita di questo Paese.<\/p>\n<\/div><div class=\"section__text section__text--center intro-animation intro-animation--bottom\">\n<h3>\u00abInizialmente mi immergo il pi\u00f9 possibile nelle origini della moneta stessa, nella sua storia e bellezza.\u00bb<\/h3>\n<\/div><div class=\"section__teaser_special\"><div class=\"teaser_special row_simple reverse middle-xs \"><div class=\"teaser_special__media col-l-6 col-xs-12 intro-animation-mobile\"><div class=\"picture_container\"><picture><source srcset=\"https:\/\/www.sondermuenze.ch\/wp-content\/uploads\/web-hq-sondermuenze-chiara-muenzen-960x850px.jpg\"><img decoding=\"async\" src=\"https:\/\/www.sondermuenze.ch\/wp-content\/uploads\/web-hq-sondermuenze-chiara-muenzen-960x850px.jpg\" alt=\"Chiara Principe M\u00fcnz Design\" width=\"960\" height=\"850\"\/><\/picture><\/div><\/div><div class=\"teaser_special__content col-l-6 col-xs-12 intro-animation intro-animation--right\"><div class=\"teaser_special__content__inside\"><p><strong>Senza rivelarne i dettagli: cosa rappresenta il design della nuova moneta da Lei ideato?<br \/>\n<\/strong>La moneta per il centenario del Vreneli da 100 franchi rappresenta una nazione saldamente ancorata ai propri valori storici e culturali, che non teme di guardare al futuro forte dei propri valori e della propria identit\u00e0. La tradizione sar\u00e0 la protagonista, visto che la storia \u00e8 al cuore del tema. Su una delle due facce avremo un\u2019interpretazione moderna e classica al contempo, che racchiude in chiave originale i simboli nazionali preservati nel corso degli ultimi 100 anni. Sono i simboli che rappresentano tutt\u2019oggi la forza e l\u2019unicit\u00e0 della cultura svizzera.<\/p>\n<\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>Chiara Principe<\/strong><br \/>\n\u00e8 un\u2019artista riconosciuta originaria di Roma, scultrice e designer di monete. Ha studiato scultura e successivamente coniazione di monete e medaglie alla Scuola dell\u2019Arte della Medaglia della sua citt\u00e0 natale. La sua carriera inizi\u00f2 dopo che nel 2007 raggiunse la fase finale di un concorso di design indetto dalla Zecca giapponese, con un progetto sul riscaldamento globale e sul Protocollo di Kyoto.<\/p>\n<p>Dal 2013 lavora come designer di monete libera professionista per diverse grandi zecche internazionali e private. Le sue opere ornano le monete di molti Paesi. I suoi disegni celebrano spesso la bellezza femminile. Trattano temi come le donne, i bambini, le famiglie e la terra e sono ampiamente ammirati per la loro originalit\u00e0, dinamicit\u00e0, versatilit\u00e0 e stravaganza.<\/p>\n<p>Chiara \u00e8 particolarmente nota per le numerose monete, medaglie e francobolli che ha ideato e che realizza dal 2012 per la Citt\u00e0 del Vaticano e la Repubblica di San Marino. Dal 2019 lavora anche per Powercoin (in Italia).<\/p>\n<\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]<div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p>La sua serie di monete \u00abEvil Within\u00bb inizi\u00f2 con la sua opera pionieristica \u00abPandora\u2019s Box\u00bb, una moneta emessa nel 2019 per la Repubblica di Palau. L\u2019artista ha anche disegnato monete con storie per bambini dai risvolti cupi come H\u00e4nsel und Gretel e Cappuccetto Rosso. Dal 2020 disegna le monete per la \u00abEast India Company\u00bb di Londra, emesse per il territorio oltremare britannico di Sant\u2019Elena. Tra queste si annovera una moneta neoclassica da due libbre con due eleganti figure femminili, coniata per il giubileo di platino della defunta regina Elisabetta II. A questa seguono la serie di monete moderne \u00abTrade Dollars\u00bb, ispirata agli originali dollari commerciali del 19\u00b0 secolo, e la serie \u00abLucky Angel\u00bb, che prende spunto dal design della moneta francese da 20 franchi con l\u2019angelo d\u2019oro, realizzata dal 14\u00b0 incisore generale della zecca di Parigi, Augustin Dupr\u00e9. Tra le opere pi\u00f9 recenti si annoverano la sua ultima moneta raffigurante un angelo, due diverse monete da 2 euro, emesse a gennaio dal Lussemburgo, e un tondo realizzato in occasione dell\u2019anno del drago per Asahi Refining.<\/p>\n<\/div>[\/vc_column_inner][\/vc_row_inner]<div class=\"section__button section__button--center intro-animation intro-animation--bottom\"><div class=\"button button--arrow button--filled\"><a href=\"http:\/\/chiaraprincipecoindesign.com\" class=\"full\" target=\"_blank\" rel=\"noopener noreferrer\" >chiaraprincipecoindesign.com<\/a><span><svg class=\"icon icon--arrow icon--arrow-left\"><use href=\"#icon_arrow\"><\/use><\/svg><span>chiaraprincipecoindesign.com<\/span><svg class=\"icon icon--arrow icon--arrow-right\"><use href=\"#icon_arrow\"><\/use><\/svg><\/span><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"template":"","class_list":["post-7993","magazin","type-magazin","status-publish","hentry","thema-monete-speciali"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sondermuenze.ch\/it\/wp-json\/wp\/v2\/magazin\/7993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sondermuenze.ch\/it\/wp-json\/wp\/v2\/magazin"}],"about":[{"href":"https:\/\/www.sondermuenze.ch\/it\/wp-json\/wp\/v2\/types\/magazin"}],"version-history":[{"count":7,"href":"https:\/\/www.sondermuenze.ch\/it\/wp-json\/wp\/v2\/magazin\/7993\/revisions"}],"predecessor-version":[{"id":8373,"href":"https:\/\/www.sondermuenze.ch\/it\/wp-json\/wp\/v2\/magazin\/7993\/revisions\/8373"}],"wp:attachment":[{"href":"https:\/\/www.sondermuenze.ch\/it\/wp-json\/wp\/v2\/media?parent=7993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}