{"id":6903,"date":"2024-07-03T09:42:59","date_gmt":"2024-07-03T07:42:59","guid":{"rendered":"https:\/\/www.sondermuenze.ch\/?post_type=magazin&#038;p=6903"},"modified":"2024-07-03T09:49:11","modified_gmt":"2024-07-03T07:49:11","slug":"entretien-avec-christian-weiss","status":"publish","type":"magazin","link":"https:\/\/www.sondermuenze.ch\/fr\/magazine\/entretien-avec-christian-weiss\/","title":{"rendered":"Entretien avec Christian Weiss"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"section__text section__text--lead section__text--center intro-animation intro-animation--bottom\">\n<h1>Interview avec Christian Weiss<\/h1>\n<p>Swissmint fait don de toutes les pi\u00e8ces nouvellement frapp\u00e9es d\u2019une ann\u00e9e donn\u00e9e au Mus\u00e9e national suisse afin que celui-ci compl\u00e8te son cabinet des monnaies. Nous vous pr\u00e9sentons Christian Weiss, le commissaire de la collection \u00abNumismatique et sceaux\u00bb du Mus\u00e9e national de Zurich.<\/p>\n<\/div><div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>Qu\u2019est-ce qui vous men\u00e9 \u00e0 la numismatique et au Mus\u00e9e national?<br \/>\n<\/strong>Apr\u00e8s avoir arr\u00eat\u00e9 mes \u00e9tudes de biologie pour \u00e9tudier l\u2019histoire et l\u2019arch\u00e9ologie, je tenais absolument \u00e0 participer \u00e0 la fouille-\u00e9cole de l\u2019Universit\u00e9 de Zurich sur le Mont Iato pr\u00e8s de Palerme. Mon professeur de l\u2019\u00e9poque m\u2019avait impos\u00e9 deux conditions: \u00e9tudier la numismatique et reprendre le poste de numismate qui allait se lib\u00e9rer. C\u2019est certainement de l\u00e0 qu\u2019est n\u00e9e ma fascination pour la numismatique. Sur le Mont Iato, je me suis rendu compte \u00e0 quel point la numismatique \u00e9tait passionnante, et, \u00e0 mon retour, j\u2019ai suivi tous les cours sur le sujet. De plus, j\u2019ai travaill\u00e9 au cabinet des monnaies de Winterthour pendant mes \u00e9tudes.<\/p>\n<p>Apr\u00e8s avoir obtenu mon dipl\u00f4me, j\u2019ai d\u00e9cid\u00e9 de faire un doctorat et j\u2019ai travaill\u00e9 dans plusieurs mus\u00e9es, notamment au Mus\u00e9e d\u2019histoire et d\u2019ethnographie de Saint-Gall et au Mus\u00e9e historique de B\u00e2le. Je suis devenu membre de la Soci\u00e9t\u00e9 suisse de numismatique et du Groupe suisse pour l\u2019\u00e9tude des trouvailles mon\u00e9taires. Apr\u00e8s avoir travaill\u00e9 au Mus\u00e9e historique de B\u00e2le, j\u2019ai d\u00e9croch\u00e9 \u00e0 la fin de 2011 un emploi fixe comme numismate aupr\u00e8s de l\u2019Inventaire des trouvailles mon\u00e9taires suisses, du service d\u2019arch\u00e9ologie du canton de Soleure et du service arch\u00e9ologique du canton de Berne. En parall\u00e8le, j\u2019enseignais, et j\u2019enseigne toujours d\u2019ailleurs, \u00e0 l\u2019Universit\u00e9 de Berne, et parfois \u00e0 l\u2019Universit\u00e9 de Zurich.<\/p>\n<p>En 2016, j\u2019ai soutenu ma th\u00e8se sur les trouvailles mon\u00e9taires et les poids m\u00e9di\u00e9vaux trouv\u00e9s sur le Mont Iato et j\u2019ai postul\u00e9 au poste de commissaire du cabinet des monnaies aupr\u00e8s du Mus\u00e9e national suisse en vue de succ\u00e9der \u00e0 Hortensia von Roten.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Le Mus\u00e9e national suisse poss\u00e8de l\u2019une des plus importantes collections de monnaies de Suisse. Quel est donc le r\u00f4le de la numismatique au sein de l\u2019\u00e9tablissement?<br \/>\n<\/strong>Je dirais m\u00eame que cette collection est la plus grande de Suisse. Notre mission est de documenter l\u2019histoire culturelle suisse aussi pr\u00e9cis\u00e9ment que possible au moyen d\u2019objets. Nous documentons toute l\u2019histoire de la fabrication des monnaies en Suisse, de l\u2019\u00e9poque celte aux temps modernes, nous collectionnons, conform\u00e9ment \u00e0 notre politique, des objets ayant un lien direct avec la Suisse, nous reconstruisons l\u2019histoire \u00e0 l\u2019aide de pi\u00e8ces de monnaie, mais bien s\u00fbr aussi d\u2019autres objets, et nous formons des \u00e9tudiants dans le domaine de la numismatique scientifique. Nous cr\u00e9ons en outre des expositions et apportons notre aide lors de la conception d\u2019autres expositions.<\/p>\n<\/div><div class=\"section__text section__text--center intro-animation intro-animation--bottom\">\n<h3>\u00abJe dirais m\u00eame que la collection du Mus\u00e9e national de Zurich est la plus grande de Suisse.\u00bb<\/h3>\n<\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>La numismatique scientifique? Comment d\u00e9finiriez-vous ce terme?<br \/>\n<\/strong>Dans le langage courant, on utilise aussi le terme \u00abnumismatique\u00bb pour d\u00e9signer l\u2019acte de collectionner des pi\u00e8ces et d\u2019en faire le commerce. Je pr\u00e9f\u00e8re donc parler de numismatique scientifique pour \u00e9viter toute confusion. Nous essayons de tirer le plus d\u2019informations possible des pi\u00e8ces dont nous disposons afin d\u2019acqu\u00e9rir de nouvelles connaissances, qu\u2019elles concernent l\u2019histoire mon\u00e9taire, l\u2019histoire \u00e9conomique ou l\u2019histoire publique. Nous essayons de comprendre ce que l\u2019argent repr\u00e9sentait pour l\u2019\u00eatre humain, la classe dirigeante et la soci\u00e9t\u00e9. En d\u00e9terminant quelles pi\u00e8ces \u00e9taient valables dans quelles r\u00e9gions, nous pouvons r\u00e9pondre \u00e0 des questions concernant les relations commerciales, les interactions sociales et les structures de l\u2019\u00e9poque.<\/p>\n<p>Ces aspects m\u2019int\u00e9ressent plus que le fait de collectionner des pi\u00e8ces. N\u00e9anmoins, collectionner des monnaies est \u00e9troitement li\u00e9 \u00e0 la numismatique scientifique. Nous avons besoin d\u2019une quantit\u00e9 suffisante d\u2019objets pour pouvoir documenter l\u2019histoire. En fait, collectionner des pi\u00e8ces est la base de la numismatique scientifique.<\/p>\n\n<p><strong>Que fait le commissionnaire d\u2019une exposition numismatique?<\/strong><br \/>\nAu Mus\u00e9e national de Zurich, je suis charg\u00e9 de g\u00e9rer la collection \u00abNumismatique et sceaux\u00bb, de d\u00e9terminer ce que nous voulons y ajouter et ce qu\u2019il faut encore explorer. L\u2019id\u00e9e est de traiter et transmettre les informations que nous fournissent les objets \u00e0 propos de l\u2019histoire. Je m\u2019occupe aussi de num\u00e9riser notre collection. J\u2019organise en outre des expositions et j\u2019apporte mon soutien \u00e0 d\u2019autres domaines en leur fournissant des objets numismatiques qui peuvent aider \u00e0 illustrer un th\u00e8me lors d\u2019une exposition. Les \u00e9changes avec les scientifiques mais aussi avec le grand public sont tr\u00e8s int\u00e9ressants. Nous sommes l\u2019interlocuteur de ces deux groupes pour toutes les questions relatives aux monnaies et \u00e0 l\u2019histoire mon\u00e9taire. Je conseille la biblioth\u00e8que du Mus\u00e9e national suisse lors de nouvelles acquisitions, afin de garantir que la collection d\u2019ouvrages de numismatique, qui est certainement la plus riche de Suisse, conserve toute sa pertinence \u00e0 l\u2019avenir. Je conseille \u00e9galement les mus\u00e9es qui poss\u00e8dent une collection numismatique, mais pas leur propre d\u00e9par\u00adtement de numismatique, et je me tiens \u00e0 la disposition des autorit\u00e9s douani\u00e8res ou p\u00e9nales pour des expertises. Lorsqu\u2019une estimation est n\u00e9cessaire, nous renvoyons aux marchands de monnaies, car le Mus\u00e9e national suisse n\u2019en effectue en principe pas.<\/p>\n\n<h3>\u00abPersonnellement, j\u2019appr\u00e9cie les pi\u00e8ces qui deviennent int\u00e9ressantes de par leur histoire.\u00bb<\/h3>\n\n<p><strong>Quelle est l\u2019importance des objets numismatiques expos\u00e9s?<br \/>\n<\/strong>Les objets numismatiques sont en g\u00e9n\u00e9ral un volet d\u2019une exposition plus vaste. Ils sont expos\u00e9s lorsqu\u2019ils aident \u00e0 illustrer un th\u00e8me. Voici deux exemples qui permettent d\u2019expliquer le r\u00f4le des objets numismatiques dans une exposition:<\/p>\n<p>\u2013 Pour l\u2019exposition permanente sur l\u2019histoire suisse, nous avons align\u00e9 des pi\u00e8ces de 1 franc, une par mill\u00e9sime. Cette pr\u00e9sentation illustre l\u2019histoire de la Suisse et de cette monnaie. Le franc est la monnaie moderne qui conna\u00eet la plus longue histoire non interrompue du monde. Depuis que la premi\u00e8re pi\u00e8ce a \u00e9t\u00e9 frapp\u00e9e, seules des modifications mineures ont \u00e9t\u00e9 effectu\u00e9es. Pour le reste, la pi\u00e8ce n\u2019a pas chang\u00e9. Cette pi\u00e8ce symbolise bien s\u00fbr aussi la Suisse et met en avant la force du franc suisse.<\/p>\n<p>\u2013 Peu apr\u00e8s qu\u2019elle a \u00e9t\u00e9 frapp\u00e9e par Swissmint, nous avons int\u00e9gr\u00e9 la monnaie sp\u00e9ciale \u00ab50 ans du droit de vote des femmes suisses\u00bb \u00e0 l\u2019exposition permanente \u00abLa Suisse. C\u2019est quoi?\u00bb inaugur\u00e9e en 2022 au Ch\u00e2teau de Prangins. Nous avons ainsi pu pr\u00e9senter le th\u00e8me du droit de vote des femmes sous une forme diff\u00e9rente.<\/p>\n\n<p><strong>Vous recevez r\u00e9guli\u00e8rement des nouvelles pi\u00e8ces de Swissmint. Quelles autres sources utilisez-vous pour compl\u00e9ter votre collection?<br \/>\n<\/strong>Outre les monnaies de Swissmint, nous recevons des dons et achetons occasionnellement des objets qu\u2019on nous propose. Dans les deux cas, nous examinons les pi\u00e8ces en d\u00e9tail. Lorsqu\u2019il s\u2019agit de dons, nous d\u00e9terminons si les objets ont bien leur place dans notre collection et v\u00e9rifions si nous les poss\u00e9dons d\u00e9j\u00e0. Notre but n\u2019est pas d\u2019en accumuler le plus possible. Si une pi\u00e8ce ne nous aide pas \u00e0 mieux illustrer les diff\u00e9rentes facettes de l\u2019histoire culturelle suisse, une donation n\u2019a de sens ni \u00e0 nos yeux, ni \u00e0 ceux du donateur. Lorsque nous achetons des pi\u00e8ces, nous devons faire preuve d\u2019une grande diligence. Nous v\u00e9rifions non seulement que les objets ont leur place dans notre collection, mais aussi que le prix est correct et la provenance \u00e9tablie.<\/p>\n<\/div>[vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;]<div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>\u00cates-vous un collectionneur?<\/strong><br \/>\nNon, je ne suis pas un collectionneur. Enfant, j\u2019ai collectionn\u00e9 les canettes de Schweppes pendant une tr\u00e8s courte p\u00e9riode, mais c\u2019\u00e9tait probablement plut\u00f4t pour imiter mon fr\u00e8re, qui collectionnait les canettes de Coca-Cola. Collectionner pour collectionner ne m\u2019int\u00e9resse pas. Mon but est d\u2019en apprendre davantage, de d\u00e9couvrir ce que r\u00e9v\u00e8le un objet. Il me suffit d\u2019avoir acc\u00e8s aux objets, je n\u2019ai pas besoin de les poss\u00e9der. Bien que je ne sois pas un collectionneur, je suis fascin\u00e9 par cette activit\u00e9: le Mus\u00e9e national suisse poss\u00e8de des collections que des particuliers ont amass\u00e9es au cours de leur vie avant de lui en faire don. Les monnaies de ces collections ne nous en apprennent pas seulement beaucoup sur leur propre histoire, mais aussi sur les r\u00e9flexions du collectionneur \u00e0 leur \u00e9gard.<\/p>\n<\/div>[\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;]<div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>Quelles pi\u00e8ces suisses vous plaisent le plus?<br \/>\n<\/strong>Personnellement, j\u2019appr\u00e9cie les pi\u00e8ces qui deviennent int\u00e9ressantes de par leur histoire. Il peut s\u2019agir de monnaies qui sont exceptionnelles pour des raisons li\u00e9es \u00e0 la frappe ou de pi\u00e8ces qui livrent des informations importantes sur l\u2019histoire.<\/p>\n<p>\u2013 Ces pi\u00e8ces exceptionnelles apparaissent \u00e0 la suite d\u2019innovations techniques ou d\u2019\u00e9v\u00e9nements politiques, mais elles peuvent aussi se distinguer par les mat\u00e9riaux ou les processus de fabrication utilis\u00e9s. En g\u00e9n\u00e9ral, les sp\u00e9cialistes ont besoin d\u2019un peu de temps pour frapper les pi\u00e8ces dans la qualit\u00e9 requise. Je trouve les monnaies fabriqu\u00e9es durant ces p\u00e9riodes de transition particuli\u00e8rement int\u00e9ressantes.<\/p>\n<p>\u2013 Les pi\u00e8ces qui peuvent fournir des informations importantes sur l\u2019histoire sont des pi\u00e8ces qui, au premier abord, paraissent souvent insignifiantes et sont parfois peu attrayantes. En revanche, ce que ces pi\u00e8ces nous apprennent sur l\u2019histoire les rend fascinantes, voire uniques.<\/p>\n<\/div>[\/vc_column_inner][\/vc_row_inner]<div class=\"section__text section__text--center intro-animation intro-animation--bottom\">\n<h3>Trois pi\u00e8ces qui ont fourni des informations\u00a0 importantes sur\u00a0l\u2019histoire<\/h3>\n<\/div><div class=\"section__image section__image--center intro-animation intro-animation--bottom\"><div class=\"picture_container\"><picture><source media=\"(min-width: 768px)\" srcset=\"https:\/\/www.sondermuenze.ch\/wp-content\/uploads\/swissmint-wissenswertes-interview-weiss-muenzen.jpg\"><source media=\"(max-width: 767.98px)\" srcset=\"https:\/\/www.sondermuenze.ch\/wp-content\/uploads\/swissmint-wissenswertes-interview-weiss-muenzen-768x240.jpg\"><img decoding=\"async\" src=\"https:\/\/www.sondermuenze.ch\/wp-content\/uploads\/swissmint-wissenswertes-interview-weiss-muenzen.jpg\" alt=\"Trois pi\u00e8ces qui ont fourni des informations importantes sur l\u2019histoire\" width=\"1280\" height=\"400\" \/><\/picture><\/div><\/div>[vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;]<div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>Inv. M-6678 <\/strong><br \/>\n<strong>Royaume m\u00e9rovingien, <\/strong><strong>Thierry II (596\u2013613), triens s. d. <\/strong><strong>(autour de 600)<\/strong><\/p>\n<p><strong>Atelier:<\/strong> Vindonissa (Windisch)<br \/>\n<strong>Avers:<\/strong> VINDONISSE FITVR\u2009; buste diad\u00e9m\u00e9 \u00e0 droite<br \/>\n<strong>Revers:<\/strong> TVTA MONE[TA]R[I]VS; croix pos\u00e9e sur un triangle, globule en dessous<br \/>\n<strong>Divers:<\/strong> \u00d8 11,0\u2009mm. 1,22\u2009g. 330\u00b0. Or, frapp\u00e9e.<\/p>\n<p>Ce triens prouve qu\u2019il existait encore un centre r\u00e9gional dot\u00e9 de sa propre monnaie \u00e0 Vindonissa vers 600 apr\u00e8s J.-C. Il s\u2019agit d\u2019un \u00e9l\u00e9ment important de la mosa\u00efque que constitue l\u2019histoire de la seigneurie du haut Moyen \u00c2ge sur le territoire de la Suisse actuelle. On ne dispose en effet que de connaissances lacunaires sur cette p\u00e9riode.<\/p>\n\n<p><strong>Inv. M-13456<\/strong><br \/>\n<strong>Schwytz, canton. Angster frapp\u00e9 d\u2019un seul c\u00f4t\u00e9 s. d. (1506\u20131529)<\/strong><\/p>\n<p><strong>Atelier:<\/strong> Bellinzone?<br \/>\n<strong>Averse<\/strong>: S\u2009=\u2009V; buste de saint Martin de face<br \/>\n<span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\"><strong>Divers:<\/strong> \u00d8 14,0\u2009mm. 0,28\u2009g. <\/span>Billon, frapp\u00e9e<\/p>\n<p>Pendant longtemps, Schwyz ne disposait pas de sa propre monnaie. C\u2019est \u00e0 l\u2019\u00e9poque o\u00f9 le canton poss\u00e9dait la seigneurie de Bellinzone avec Uri et Nidwald qu\u2019il a commenc\u00e9 \u00e0 frapper ses premi\u00e8res pi\u00e8ces, conjointement avec les deux autres cantons. La di\u00e8te f\u00e9d\u00e9rale de mars 1506 s\u2019\u00e9tant oppos\u00e9e \u00e0 la nouvelle monnaie, Schwytz s\u2019est retir\u00e9 de cette entreprise commune et a commenc\u00e9 \u00e0 battre sa propre monnaie. La seule diff\u00e9rence entre le nouvel Angster et l\u2019Angster frapp\u00e9 avec les autres cantons est que le S\u2009=\u2009M d\u00e9signant saint Martin a \u00e9t\u00e9 transform\u00e9 en S\u2009=\u2009V, soit Svit(ensis) (=\u2009Schwytz[ois]). Cette pi\u00e8ce \u00e9tait certainement destin\u00e9e \u00e0 \u00eatre mise en circulation au nord des Alpes. Schwytz ne disposant toutefois pas d\u2019atelier de frappe dans la r\u00e9gion, les premi\u00e8res monnaies du canton ont probablement \u00e9t\u00e9 frapp\u00e9es \u00e0 Bellinzone.<\/p>\n<\/div>[\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;]<div class=\"section__text section__text--center intro-animation intro-animation--bottom\"><p><strong>Inv. M-4233 <\/strong><br \/>\n<strong>Duch\u00e9 de Souabe, pi\u00e8ce de la di\u00e8te de cour, empereur Conrad II (1027\u20131039), denier s. d. <\/strong><br \/>\n<strong>(1030\u20131034)<\/strong><\/p>\n<p><strong>Atelier:<\/strong> Zurich<br \/>\n<strong style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Avers:<\/strong><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\"> +\u2009CHVNRADVS IMPER; couronne salique<br \/>\n<\/span><strong>Revers:<\/strong> +\u2009TVREGVM; r\u00e9sidence imp\u00e9riale de Zurich, fa\u00e7ade sud<br \/>\n<strong>Divers:<\/strong> \u00d8 19,9\u2009mm. 0,63\u2009g. 315\u00b0. Argent, frapp\u00e9e.<\/p>\n<p>On distingue un b\u00e2timent s\u00e9culier sur le revers du denier de l\u2019empereur Conrad II. Il s\u2019agit probablement de la r\u00e9sidence imp\u00e9riale du Lindenhof \u00e0 Zurich, \u00e0 ses d\u00e9buts. Le denier sur lequel figurent une couronne et un b\u00e2timent repr\u00e9sentatif est une fa\u00e7on pour l\u2019empereur de faire \u00e9talage de son pouvoir dans une r\u00e9gion qui s\u2019\u00e9tait rebell\u00e9e contre l\u2019empire sous le r\u00e8gne du duc Ernest II.<\/p>\n<\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"template":"","class_list":["post-6903","magazin","type-magazin","status-publish","hentry","thema-faits-interessants"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sondermuenze.ch\/fr\/wp-json\/wp\/v2\/magazin\/6903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sondermuenze.ch\/fr\/wp-json\/wp\/v2\/magazin"}],"about":[{"href":"https:\/\/www.sondermuenze.ch\/fr\/wp-json\/wp\/v2\/types\/magazin"}],"version-history":[{"count":5,"href":"https:\/\/www.sondermuenze.ch\/fr\/wp-json\/wp\/v2\/magazin\/6903\/revisions"}],"predecessor-version":[{"id":7130,"href":"https:\/\/www.sondermuenze.ch\/fr\/wp-json\/wp\/v2\/magazin\/6903\/revisions\/7130"}],"wp:attachment":[{"href":"https:\/\/www.sondermuenze.ch\/fr\/wp-json\/wp\/v2\/media?parent=6903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}