{"id":857,"date":"2023-01-03T08:31:22","date_gmt":"2023-01-03T07:31:22","guid":{"rendered":"https:\/\/www.sondermuenze.ch\/?post_type=magazin&#038;p=857"},"modified":"2023-02-08T08:40:53","modified_gmt":"2023-02-08T07:40:53","slug":"kleinkunstwerke-gepraegt-fuer-ein-ganzes-leben","status":"publish","type":"magazin","link":"https:\/\/www.sondermuenze.ch\/de\/magazin\/kleinkunstwerke-gepraegt-fuer-ein-ganzes-leben\/","title":{"rendered":"Kleinkunstwerke,  gepr\u00e4gt f\u00fcr ein ganzes Leben"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"section__text section__text--lead section__text--center intro-animation intro-animation--bottom\">\n<h1>Kleinkunstwerke, gepr\u00e4gt f\u00fcr ein ganzes Leben<\/h1>\n<p>Was bedeuten uns Gedenk- und Sondermu\u0308nzen? Was fasziniert an ihnen? Auf jeden Fall sind sie da, um zu bleiben. Auch in einer Welt, in der das Greif- und Unmittelbare immer mehr der virtuellen Realit\u00e4t zu weichen scheint.<\/p>\n<\/div>[vc_row_inner][vc_column_inner width=&#8220;1\/2&#8243;]<div class=\"section__text intro-animation intro-animation--bottom\"><p><strong>Einzigartiges Ged\u00e4chtnis der Schweiz<br \/>\n<\/strong>Sonderm\u00fcnzen dokumentieren vergangene Zeiten und wichtige Geschehnisse. Und sie werden selbst zu einem Teil der (Schweizer) Geschichte, von der sie zeugen. Sie sind unser kollektives Ged\u00e4chtnis, materialisiert und f\u00fcr die Ewigkeit in Gold, Silber, Platin oder Bimetall gepr\u00e4gt.<\/p>\n<p><strong>Wundersch\u00f6ne Kleinstkunstwerke<br \/>\n<\/strong>Jede einzelne unserer M\u00fcnzen ist in feinster Handarbeit hergestellt worden, sei es der Stempel f\u00fcr die Produktion oder die M\u00fcnze selbst. Gerade die h\u00f6chsten Pr\u00e4gequalit\u00e4ten wie etwa \u00abPolierte Platte\u00bb bestechen nicht nur durch ihre sorgf\u00e4ltige, harmonische Gesamtgestaltung, sondern auch durch die optimale Sichtbarkeit der herausgearbeiteten Details.<\/p>\n<p><strong>Etwas Best\u00e4ndiges gegen die Verg\u00e4nglichkeit<br \/>\n<\/strong>Ob Nennwert, emotionaler Wert, Materialwert, symbolischer Wert oder Erinnerungswert: M\u00fcnzen scheinen etwas mit unserer Werthaltung oder Wertsch\u00e4tzung zu tun zu haben. Sie haben einerseits einen \u00abGeld-Wert\u00bb und stellen andererseits einen \u00fcbergeordneten, die Zeit \u00fcberdauernden Wert dar. Einfach gesagt: Moden kommen und gehen, M\u00fcnzen bleiben.<\/p>\n<\/div>[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;]<div class=\"section__text intro-animation intro-animation--bottom\"><p><strong>M\u00fcnzen pr\u00e4gen Gemeinschaften, Geschichten und Erinnerungen<br \/>\n<\/strong>Jede M\u00fcnze erz\u00e4hlt eine Geschichte \u00fcber ihren Besitzer, \u00fcber das Schenken und Beschenktwerden, \u00fcber das Erhalten und Best\u00e4rken von Freundschaften und famili\u00e4ren Banden. Wer ein Goldvreneli besitzt, erinnert sich in der Regel auch daran, wer es ihm zu welchem Anlass geschenkt hat. Und freut sich vielleicht ein Leben lang dar\u00fcber.<\/p>\n<p><strong>Optische und haptische Erlebnisse<br \/>\n<\/strong>M\u00fcnzen aus Edelmetall in gepr\u00e4gter Form sind sinnliche Erlebnisse der besonderen Art. Ihre Brillanz macht sie zum unwiderstehlichen Hingucker, und sie sind kunstvolle Kultobjekte zum Anfassen. Spontan tastet man mit den Fingerkuppen \u00fcber ihre Fl\u00e4chen und Kanten, um die feinen Reliefs zu sp\u00fcren, gerne wiegt man sie in der Hand, um ihre Wertigkeit f\u00fchlen und absch\u00e4tzen zu k\u00f6nnen.<\/p>\n<\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"template":"","class_list":["post-857","magazin","type-magazin","status-publish","hentry","thema-sondermuenzen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sondermuenze.ch\/de\/wp-json\/wp\/v2\/magazin\/857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sondermuenze.ch\/de\/wp-json\/wp\/v2\/magazin"}],"about":[{"href":"https:\/\/www.sondermuenze.ch\/de\/wp-json\/wp\/v2\/types\/magazin"}],"version-history":[{"count":3,"href":"https:\/\/www.sondermuenze.ch\/de\/wp-json\/wp\/v2\/magazin\/857\/revisions"}],"predecessor-version":[{"id":2838,"href":"https:\/\/www.sondermuenze.ch\/de\/wp-json\/wp\/v2\/magazin\/857\/revisions\/2838"}],"wp:attachment":[{"href":"https:\/\/www.sondermuenze.ch\/de\/wp-json\/wp\/v2\/media?parent=857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}